{"id":1886,"date":"2022-02-17T10:37:22","date_gmt":"2022-02-17T13:37:22","guid":{"rendered":"https:\/\/www.xlabs.com.br\/blog\/?p=1886"},"modified":"2022-02-17T13:26:51","modified_gmt":"2022-02-17T16:26:51","slug":"seguranca-da-informacao-x-gestao-de-privacidade","status":"publish","type":"post","link":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/","title":{"rendered":"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade"},"content":{"rendered":"\n<p>Com as novas regulamenta\u00e7\u00f5es e a incid\u00eancia cada vez maior de riscos cibern\u00e9ticos, a Seguran\u00e7a da Informa\u00e7\u00e3o e a Gest\u00e3o de Privacidade se tornaram temas recorrentes nas empresas e, em especial, nos setores de TI.<\/p>\n\n\n\n<p>E para entender melhor a relev\u00e2ncia de ambos e identificar as suas principais diferen\u00e7as, n\u00f3s preparamos este artigo com informa\u00e7\u00f5es \u00fateis e dicas pr\u00e1ticas, que servir\u00e3o de base para o seu entendimento.<\/p>\n\n\n\n<p>Sendo assim, vamos direto aos pontos. <strong>Boa leitura!<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3>Qual a rela\u00e7\u00e3o entre Seguran\u00e7a da Informa\u00e7\u00e3o e Gest\u00e3o de Privacidade?<\/h3>\n\n\n\n<p>Atualmente, a privacidade de dados \u00e9 um dos assuntos e preocupa\u00e7\u00f5es mais debatidos na esfera digital e isso foi impulsionado com a <a href=\"https:\/\/www.xlabs.com.br\/blog\/lgpd-e-a-protecao-de-dados\/\" target=\"_blank\" rel=\"noreferrer noopener\">cria\u00e7\u00e3o da nova LGPD<\/a>.<\/p>\n\n\n\n<p>Por\u00e9m, manter uma boa Gest\u00e3o de Privacidade vai muito al\u00e9m da quest\u00e3o de prote\u00e7\u00e3o de dados, mas tamb\u00e9m de um compromisso e responsabilidade sobre os dados de quem confiou \u00e0 sua empresa.<\/p>\n\n\n\n<p>Afinal, um poss\u00edvel vazamento pode acarretar em preju\u00edzos, tanto financeiros, como para a pr\u00f3pria imagem do neg\u00f3cio.<\/p>\n\n\n\n<p>Logo, a Gest\u00e3o de Privacidade exige conhecimentos e cuidados espec\u00edficos sobre a Seguran\u00e7a da Informa\u00e7\u00e3o, permitindo assim que a empresa cumpra as devidas regulamenta\u00e7\u00f5es, mas tamb\u00e9m garante o uso correto e a prote\u00e7\u00e3o desses dados no dia a dia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3>Qual \u00e9 o papel da Gest\u00e3o de Privacidades sobre a Seguran\u00e7a de Informa\u00e7\u00f5es?<\/h3>\n\n\n\n<p>Ap\u00f3s a cria\u00e7\u00e3o da LGPD, novos cargos, como o DPO (Data Protection Officer) e o CSO (Chief Security Officer) surgiram no mercado de TI, agregando fun\u00e7\u00f5es e responsabilidades que s\u00e3o indispens\u00e1veis nos dias de hoje.<\/p>\n\n\n\n<p>Assim, cabe a estes profissionais implementarem e cuidarem da Gest\u00e3o de Privacidade, garantindo a devida seguran\u00e7a de dados e informa\u00e7\u00f5es de seus usu\u00e1rios. E isso se faz a partir de algumas obriga\u00e7\u00f5es, tais como:<\/p>\n\n\n\n<ul><li>Conhecimento e cumprimento das exig\u00eancias estabelecidas pela lei;<\/li><li>Cria\u00e7\u00e3o e implementa\u00e7\u00e3o de guias sobre boas pr\u00e1ticas de seguran\u00e7a cibern\u00e9tica na empresa;<\/li><li>Treinamento e orienta\u00e7\u00e3o sobre pol\u00edticas de seguran\u00e7a de dados;<\/li><li>Investimento e implementa\u00e7\u00e3o de solu\u00e7\u00f5es adequadas para a prote\u00e7\u00e3o cibern\u00e9tica da empresa;<\/li><li>Monitoramento e aperfei\u00e7oamento das boas pr\u00e1ticas de seguran\u00e7a.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3>Qual a melhor ferramenta para a Gest\u00e3o de Privacidade?<\/h3>\n\n\n\n<p>Como bem destacado, a seguran\u00e7a da informa\u00e7\u00e3o foi um assunto impulsionado pela cria\u00e7\u00e3o da LDPG e originou uma corrida das empresas pela adapta\u00e7\u00e3o \u00e0s exig\u00eancias.<\/p>\n\n\n\n<p>No entanto, \u00e9 muito importante ressaltar que a gest\u00e3o de privacidade n\u00e3o deve se resumir \u00e0 uma simples necessidade de cumprir as exig\u00eancias estabelecidas por lei, mas tamb\u00e9m de garantir a devida prote\u00e7\u00e3o desses dados.<\/p>\n\n\n\n<p>E, hoje, falar sobre isso, inevitavelmente nos remete ao <a href=\"https:\/\/www.xlabs.com.br\/blog\/ciberataques-em-2021-conheca-alguns-casos-e-estatisticas\/\" target=\"_blank\" rel=\"noreferrer noopener\">aumento gradativo da incid\u00eancia de ataques cibern\u00e9ticos<\/a> em todas as esferas de neg\u00f3cios.<\/p>\n\n\n\n<p>Por esse motivo, o <a href=\"https:\/\/conteudo.xlabs.com.br\/versao-gratuita-de-avaliacao?utm_campaign=WAF&amp;utm_source=ppc&amp;utm_term=waf%20firewall&amp;utm_campaign=Web+Armor+Firewall&amp;utm_source=adwords&amp;utm_medium=ppc&amp;hsa_acc=4315376531&amp;hsa_cam=13873164676&amp;hsa_grp=128382221647&amp;hsa_ad=533118138676&amp;hsa_src=g&amp;hsa_tgt=aud-1429448649768:kwd-296251530220&amp;hsa_kw=waf%20firewall&amp;hsa_mt=b&amp;hsa_net=adwords&amp;hsa_ver=3&amp;gclid=CjwKCAiAl-6PBhBCEiwAc2GOVFJs64xkwGHt0nryhfdVHrG2ZSzQD9LKheSvox487HNiJnZSJPuMGhoCMZwQAvD_BwE\" target=\"_blank\" rel=\"noreferrer noopener\">WAF (Web Application Firewall)<\/a> tem sido considerado um investimento fundamental e a melhor solu\u00e7\u00e3o para a prote\u00e7\u00e3o de dados em tempos de ataques consecutivos.<\/p>\n\n\n\n<p>Em resumo, esse \u00e9 um pequeno panorama sobre a rela\u00e7\u00e3o entre Gest\u00e3o de Privacidade e Seguran\u00e7a da Informa\u00e7\u00e3o, e como o tema ganhou relev\u00e2ncia nos \u00faltimos anos, n\u00e3o apenas por quest\u00f5es de cumprimento das exig\u00eancias da LDPG, como tamb\u00e9m por fatores estrat\u00e9gicos de prote\u00e7\u00e3o contra ciberataques.<\/p>\n\n\n\n<p>Curtiu? Quer saber mais sobre o tema e conferir as dicas pr\u00e1ticas para otimizar a sua gest\u00e3o de privacidade?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-956e9ed0-9975-44bd-9fc3-6f90f73db0ca\"><span class=\"hs-cta-node hs-cta-956e9ed0-9975-44bd-9fc3-6f90f73db0ca\" id=\"hs-cta-956e9ed0-9975-44bd-9fc3-6f90f73db0ca\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/6339257\/956e9ed0-9975-44bd-9fc3-6f90f73db0ca\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-956e9ed0-9975-44bd-9fc3-6f90f73db0ca\" style=\"border-width:0px;\" height=\"214\" width=\"800\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/6339257\/956e9ed0-9975-44bd-9fc3-6f90f73db0ca.png\" alt=\"Guia Definitivo sobre Privacidade de Dados\"><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(6339257, '956e9ed0-9975-44bd-9fc3-6f90f73db0ca', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\n","protected":false},"excerpt":{"rendered":"<p>Com as novas regulamenta\u00e7\u00f5es e a incid\u00eancia cada vez maior de riscos cibern\u00e9ticos, a Seguran\u00e7a da Informa\u00e7\u00e3o e a Gest\u00e3o de Privacidade se tornaram temas recorrentes nas empresas e, em especial, nos setores de TI. E para entender melhor a relev\u00e2ncia de ambos e identificar as suas principais diferen\u00e7as, n\u00f3s preparamos este artigo com informa\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":1889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade &ndash; XLabs Security Blog<\/title>\n<meta name=\"description\" content=\"As novas normas da LGPD vieram com grandes mudan\u00e7as na Seguran\u00e7a da Informa\u00e7\u00e3o e Gest\u00e3o de Privacidade. Saiba mais sobre a import\u00e2ncia e o papel imposto por elas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade &ndash; XLabs Security Blog\" \/>\n<meta property=\"og:description\" content=\"As novas normas da LGPD vieram com grandes mudan\u00e7as na Seguran\u00e7a da Informa\u00e7\u00e3o e Gest\u00e3o de Privacidade. Saiba mais sobre a import\u00e2ncia e o papel imposto por elas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/\" \/>\n<meta property=\"og:site_name\" content=\"XLabs Security Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/xlabs\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T13:37:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-17T16:26:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2022\/02\/xLabs-blogpost-Seguranca-da-Informacao-Vs-Gestao-de-Privacidade_b.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Evelyn Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyn Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/\"},\"author\":{\"name\":\"Evelyn Rocha\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/186fa2419710709368bfa220767edb4b\"},\"headline\":\"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade\",\"datePublished\":\"2022-02-17T13:37:22+00:00\",\"dateModified\":\"2022-02-17T16:26:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/\"},\"wordCount\":613,\"publisher\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\"},\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/\",\"name\":\"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade &ndash; XLabs Security Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#website\"},\"datePublished\":\"2022-02-17T13:37:22+00:00\",\"dateModified\":\"2022-02-17T16:26:51+00:00\",\"description\":\"As novas normas da LGPD vieram com grandes mudan\u00e7as na Seguran\u00e7a da Informa\u00e7\u00e3o e Gest\u00e3o de Privacidade. Saiba mais sobre a import\u00e2ncia e o papel imposto por elas.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.xlabs.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#website\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/\",\"name\":\"XLabs Security Blog\",\"description\":\"Seguran\u00e7a da Informa\u00e7\u00e3o\",\"publisher\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.xlabs.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\",\"name\":\"XLabs Security\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png\",\"contentUrl\":\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png\",\"width\":478,\"height\":168,\"caption\":\"XLabs Security\"},\"image\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/xlabs.security\",\"https:\/\/www.linkedin.com\/company\/xlabs-security\/\",\"https:\/\/www.youtube.com\/channel\/UCPbGDmCQI7_UcAPmvVLi58g?view_as=subscriber\",\"https:\/\/www.facebook.com\/xlabs\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/186fa2419710709368bfa220767edb4b\",\"name\":\"Evelyn Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbfd8fc83a660edc367ca0dfbbb18e2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbfd8fc83a660edc367ca0dfbbb18e2e?s=96&d=mm&r=g\",\"caption\":\"Evelyn Rocha\"},\"sameAs\":[\"http:\/\/www.xlabs.com.br\"],\"url\":\"https:\/\/www.xlabs.com.br\/blog\/author\/evelyn-rocha\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade &ndash; XLabs Security Blog","description":"As novas normas da LGPD vieram com grandes mudan\u00e7as na Seguran\u00e7a da Informa\u00e7\u00e3o e Gest\u00e3o de Privacidade. Saiba mais sobre a import\u00e2ncia e o papel imposto por elas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade &ndash; XLabs Security Blog","og_description":"As novas normas da LGPD vieram com grandes mudan\u00e7as na Seguran\u00e7a da Informa\u00e7\u00e3o e Gest\u00e3o de Privacidade. Saiba mais sobre a import\u00e2ncia e o papel imposto por elas.","og_url":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/","og_site_name":"XLabs Security Blog","article_publisher":"https:\/\/www.facebook.com\/xlabs","article_published_time":"2022-02-17T13:37:22+00:00","article_modified_time":"2022-02-17T16:26:51+00:00","og_image":[{"width":1000,"height":488,"url":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2022\/02\/xLabs-blogpost-Seguranca-da-Informacao-Vs-Gestao-de-Privacidade_b.png","type":"image\/png"}],"author":"Evelyn Rocha","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Evelyn Rocha","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/#article","isPartOf":{"@id":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/"},"author":{"name":"Evelyn Rocha","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/186fa2419710709368bfa220767edb4b"},"headline":"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade","datePublished":"2022-02-17T13:37:22+00:00","dateModified":"2022-02-17T16:26:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/"},"wordCount":613,"publisher":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#organization"},"articleSection":["Artigos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/","url":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/","name":"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade &ndash; XLabs Security Blog","isPartOf":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#website"},"datePublished":"2022-02-17T13:37:22+00:00","dateModified":"2022-02-17T16:26:51+00:00","description":"As novas normas da LGPD vieram com grandes mudan\u00e7as na Seguran\u00e7a da Informa\u00e7\u00e3o e Gest\u00e3o de Privacidade. Saiba mais sobre a import\u00e2ncia e o papel imposto por elas.","breadcrumb":{"@id":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.xlabs.com.br\/blog\/seguranca-da-informacao-x-gestao-de-privacidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.xlabs.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Seguran\u00e7a da Informa\u00e7\u00e3o X Gest\u00e3o de Privacidade"}]},{"@type":"WebSite","@id":"https:\/\/www.xlabs.com.br\/blog\/#website","url":"https:\/\/www.xlabs.com.br\/blog\/","name":"XLabs Security Blog","description":"Seguran\u00e7a da Informa\u00e7\u00e3o","publisher":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.xlabs.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.xlabs.com.br\/blog\/#organization","name":"XLabs Security","url":"https:\/\/www.xlabs.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png","contentUrl":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png","width":478,"height":168,"caption":"XLabs Security"},"image":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/xlabs.security","https:\/\/www.linkedin.com\/company\/xlabs-security\/","https:\/\/www.youtube.com\/channel\/UCPbGDmCQI7_UcAPmvVLi58g?view_as=subscriber","https:\/\/www.facebook.com\/xlabs"]},{"@type":"Person","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/186fa2419710709368bfa220767edb4b","name":"Evelyn Rocha","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbfd8fc83a660edc367ca0dfbbb18e2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbfd8fc83a660edc367ca0dfbbb18e2e?s=96&d=mm&r=g","caption":"Evelyn Rocha"},"sameAs":["http:\/\/www.xlabs.com.br"],"url":"https:\/\/www.xlabs.com.br\/blog\/author\/evelyn-rocha\/"}]}},"_links":{"self":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/1886"}],"collection":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1886"}],"version-history":[{"count":6,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/1886\/revisions"}],"predecessor-version":[{"id":1893,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/1886\/revisions\/1893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/media\/1889"}],"wp:attachment":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}