{"id":1881,"date":"2022-02-22T08:09:25","date_gmt":"2022-02-22T11:09:25","guid":{"rendered":"https:\/\/www.xlabs.com.br\/blog\/?p=1881"},"modified":"2023-08-31T20:10:35","modified_gmt":"2023-08-31T23:10:35","slug":"sobre-ataques-sql-injection","status":"publish","type":"post","link":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/","title":{"rendered":"Sobre ataques: SQL Injection"},"content":{"rendered":"\n<p>Tem se tornado cada vez mais comum nos deparamos com in\u00fameras not\u00edcias de grandes empresas que se tornaram alvos de ataques cibern\u00e9ticos, na qual dados foram roubados e vazados, ou at\u00e9 mesmo, tiveram que interromper seus servi\u00e7os. Com o aumento no n\u00famero de profissionais trabalhando na modalidade home office, e em muitos casos, sem conhecimento dos protocolos e dicas de Seguran\u00e7a digital, tivemos um aumento de 50% de ciberataques contra organiza\u00e7\u00f5es em todo o mundo em 2021, segundo a<a href=\"https:\/\/www.securityreport.com.br\/overview\/estudo-aponta-alta-de-50-no-numero-de-ciberataques-em-todo-mundo-em-2021\/#.YerMav7MLIU\" target=\"_blank\" rel=\"noreferrer noopener\"> Check Point Software Brasil<\/a>. No Brasil, o levantamento apontou 62% de aumento de ciberataques por semana, em compara\u00e7\u00e3o com 2020 (967 ciberataques por semana, em m\u00e9dia).<\/p>\n\n\n\n<p>\u00c0 medida que novas amea\u00e7as est\u00e3o surgindo diariamente, conhecer e compreender como acontecem os principais tipos de ataques virtuais pode ser a diferen\u00e7a entre estar seguro ou se tornar uma v\u00edtima. E \u00e9 por isso que precisamos continuar alertando sobre amea\u00e7as e ciberataques, como \u00e9 o caso do ataque conhecido como &#8220;SQL Injection&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3><strong>Sobre o SQL Injection<\/strong><\/h3>\n\n\n\n<p>Com uma tradu\u00e7\u00e3o pr\u00f3xima a &#8220;inje\u00e7\u00e3o de SQL&#8221;, em portugu\u00eas, como o pr\u00f3prio nome j\u00e1 indica, este tipo de ataque \u00e9 baseado na manipula\u00e7\u00e3o do c\u00f3digo SQL (Structured Query Language, ou &#8220;Linguagem de Consulta Estruturada&#8221;), que \u00e9 a linguagem utilizada para troca de informa\u00e7\u00f5es entre aplicativos e bancos de dados relacionais, extremamente popular e amplamente utilizada hoje em dia. Tal manipula\u00e7\u00e3o permite que o criminoso determine de que forma essa troca de informa\u00e7\u00f5es ir\u00e1 acontecer. Ou seja, uma invas\u00e3o bem-sucedida pode resultar em acessos n\u00e3o autorizados a informa\u00e7\u00f5es confidenciais.<\/p>\n\n\n\n<p>Devido ao alt\u00edssimo n\u00famero de servidores e sites que utilizam bancos de dados, o <em>SQL Injection<\/em>&nbsp; \u00e9 considerado um dos m\u00e9todos mais comuns e antigos de ataques. As a\u00e7\u00f5es dos criminosos podem variar, resultando em um simples processo de edi\u00e7\u00e3o ou exclus\u00e3o dos dados de alguma parti\u00e7\u00e3o do banco. Especialmente em sites financeiros, \u00e9 poss\u00edvel alterar saldos de contas e desviar dinheiro de forma il\u00edcita. O ataque tamb\u00e9m permite executar a\u00e7\u00f5es em nome dos usu\u00e1rios afetados ou compilar logins comprometidos em uma lista maior para vender a outros cibercriminosos, que normalmente compram esses tipos de informa\u00e7\u00f5es visando roubo de identidade e fraudes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3><strong>Como se proteger?<\/strong><\/h3>\n\n\n\n<p>Adotar medidas de prote\u00e7\u00e3o \u00e9 essencial para manter os dados de uma corpora\u00e7\u00e3o ou sistema em seguran\u00e7a. Os ataques de SQL Injection acontecem em sistemas que est\u00e3o vulner\u00e1veis, e \u00e9 poss\u00edvel evit\u00e1-los por meio de pr\u00e1ticas de Seguran\u00e7a, tais como:<\/p>\n\n\n\n<p> \u25cf   <strong>Usar logs de seguran\u00e7a em seu servidor.<\/strong> Os logs de seguran\u00e7a s\u00e3o respons\u00e1veis por reportarem tentativas de comandos indevidos. \u00c9 de extrema import\u00e2ncia que ele seja verificado periodicamente, para garantir que as informa\u00e7\u00f5es est\u00e3o sendo capturadas.<\/p>\n\n\n\n<p>\u00a0\u25cf   <strong>N\u00e3o permitir que a conex\u00e3o com o servidor SQL seja feita com usu\u00e1rios gen\u00e9ricos.<\/strong> Propriet\u00e1rios ou administradores do banco devem ter usu\u00e1rios espec\u00edficos e acessos exclusivos.<\/p>\n\n\n\n<p>&nbsp;\u25cf   <strong>Mantenha as credenciais do banco de dados separadas e criptografadas.<\/strong> D\u00ea prefer\u00eancia a um arquivo separado e criptografado para a armazenagem. Ele vai prover mais seguran\u00e7a e, no m\u00ednimo, dificultar o trabalho dos criminosos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3><strong>Descubra qual a melhor solu\u00e7\u00e3o para o seu neg\u00f3cio<\/strong><\/h3>\n\n\n\n<p>Quer conhecer e corrigir as vulnerabilidades e falhas dos seus sistemas? A XLabs Security conta com uma equipe de pesquisadores de amea\u00e7as, especializados em encontrar vulnerabilidades, desde as mais comuns \u00e0s mais complexas, trabalhando para manter os seus sistemas protegidos.<a href=\"https:\/\/www.xlabs.com.br\/especialistas\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Fale agora mesmo com um de nossos especialistas<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tem se tornado cada vez mais comum nos deparamos com in\u00fameras not\u00edcias de grandes empresas que se tornaram alvos de ataques cibern\u00e9ticos, na qual dados foram roubados e vazados, ou at\u00e9 mesmo, tiveram que interromper seus servi\u00e7os. Com o aumento no n\u00famero de profissionais trabalhando na modalidade home office, e em muitos casos, sem conhecimento [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":1882,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[332,51,331,76],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sobre ataques: SQL Injection &ndash; XLabs Security Blog<\/title>\n<meta name=\"description\" content=\"Acompanhe nosso artigo de sobre o ataque conhecido como &quot;SQL Injection&quot;. Entenda como ele funciona e como voc\u00ea pode se proteger.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobre ataques: SQL Injection &ndash; XLabs Security Blog\" \/>\n<meta property=\"og:description\" content=\"Acompanhe nosso artigo de sobre o ataque conhecido como &quot;SQL Injection&quot;. Entenda como ele funciona e como voc\u00ea pode se proteger.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/\" \/>\n<meta property=\"og:site_name\" content=\"XLabs Security Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/xlabs\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-22T11:09:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-31T23:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2022\/02\/sobre-ataques-SQL-Injection-blog-post-xlabs-security.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Evelyn Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sobre ataques: SQL Injection &ndash; XLabs Security Blog\" \/>\n<meta name=\"twitter:description\" content=\"Acompanhe nosso artigo de sobre o ataque conhecido como &quot;SQL Injection&quot;. Entenda como ele funciona e como voc\u00ea pode se proteger.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2022\/02\/sobre-ataques-SQL-Injection-blog-post-xlabs-security.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyn Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/\"},\"author\":{\"name\":\"Evelyn Rocha\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/186fa2419710709368bfa220767edb4b\"},\"headline\":\"Sobre ataques: SQL Injection\",\"datePublished\":\"2022-02-22T11:09:25+00:00\",\"dateModified\":\"2023-08-31T23:10:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/\"},\"wordCount\":609,\"publisher\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\"},\"keywords\":[\"Inje\u00e7\u00e3o de SQL\",\"Pentest\",\"SQL\",\"SQL Injection\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/\",\"name\":\"Sobre ataques: SQL Injection &ndash; XLabs Security Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#website\"},\"datePublished\":\"2022-02-22T11:09:25+00:00\",\"dateModified\":\"2023-08-31T23:10:35+00:00\",\"description\":\"Acompanhe nosso artigo de sobre o ataque conhecido como \\\"SQL Injection\\\". Entenda como ele funciona e como voc\u00ea pode se proteger.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.xlabs.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre ataques: SQL Injection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#website\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/\",\"name\":\"XLabs Security Blog\",\"description\":\"Seguran\u00e7a da Informa\u00e7\u00e3o\",\"publisher\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.xlabs.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#organization\",\"name\":\"XLabs Security\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png\",\"contentUrl\":\"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png\",\"width\":478,\"height\":168,\"caption\":\"XLabs Security\"},\"image\":{\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/xlabs.security\",\"https:\/\/www.linkedin.com\/company\/xlabs-security\/\",\"https:\/\/www.youtube.com\/channel\/UCPbGDmCQI7_UcAPmvVLi58g?view_as=subscriber\",\"https:\/\/www.facebook.com\/xlabs\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/186fa2419710709368bfa220767edb4b\",\"name\":\"Evelyn Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbfd8fc83a660edc367ca0dfbbb18e2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbfd8fc83a660edc367ca0dfbbb18e2e?s=96&d=mm&r=g\",\"caption\":\"Evelyn Rocha\"},\"sameAs\":[\"http:\/\/www.xlabs.com.br\"],\"url\":\"https:\/\/www.xlabs.com.br\/blog\/author\/evelyn-rocha\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobre ataques: SQL Injection &ndash; XLabs Security Blog","description":"Acompanhe nosso artigo de sobre o ataque conhecido como \"SQL Injection\". Entenda como ele funciona e como voc\u00ea pode se proteger.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/","og_locale":"pt_BR","og_type":"article","og_title":"Sobre ataques: SQL Injection &ndash; XLabs Security Blog","og_description":"Acompanhe nosso artigo de sobre o ataque conhecido como \"SQL Injection\". Entenda como ele funciona e como voc\u00ea pode se proteger.","og_url":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/","og_site_name":"XLabs Security Blog","article_publisher":"https:\/\/www.facebook.com\/xlabs","article_published_time":"2022-02-22T11:09:25+00:00","article_modified_time":"2023-08-31T23:10:35+00:00","og_image":[{"width":1000,"height":488,"url":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2022\/02\/sobre-ataques-SQL-Injection-blog-post-xlabs-security.png","type":"image\/png"}],"author":"Evelyn Rocha","twitter_card":"summary_large_image","twitter_title":"Sobre ataques: SQL Injection &ndash; XLabs Security Blog","twitter_description":"Acompanhe nosso artigo de sobre o ataque conhecido como \"SQL Injection\". Entenda como ele funciona e como voc\u00ea pode se proteger.","twitter_image":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2022\/02\/sobre-ataques-SQL-Injection-blog-post-xlabs-security.png","twitter_misc":{"Escrito por":"Evelyn Rocha","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/#article","isPartOf":{"@id":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/"},"author":{"name":"Evelyn Rocha","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/186fa2419710709368bfa220767edb4b"},"headline":"Sobre ataques: SQL Injection","datePublished":"2022-02-22T11:09:25+00:00","dateModified":"2023-08-31T23:10:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/"},"wordCount":609,"publisher":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#organization"},"keywords":["Inje\u00e7\u00e3o de SQL","Pentest","SQL","SQL Injection"],"articleSection":["Artigos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/","url":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/","name":"Sobre ataques: SQL Injection &ndash; XLabs Security Blog","isPartOf":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#website"},"datePublished":"2022-02-22T11:09:25+00:00","dateModified":"2023-08-31T23:10:35+00:00","description":"Acompanhe nosso artigo de sobre o ataque conhecido como \"SQL Injection\". Entenda como ele funciona e como voc\u00ea pode se proteger.","breadcrumb":{"@id":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.xlabs.com.br\/blog\/sobre-ataques-sql-injection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.xlabs.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Sobre ataques: SQL Injection"}]},{"@type":"WebSite","@id":"https:\/\/www.xlabs.com.br\/blog\/#website","url":"https:\/\/www.xlabs.com.br\/blog\/","name":"XLabs Security Blog","description":"Seguran\u00e7a da Informa\u00e7\u00e3o","publisher":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.xlabs.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.xlabs.com.br\/blog\/#organization","name":"XLabs Security","url":"https:\/\/www.xlabs.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png","contentUrl":"https:\/\/www.xlabs.com.br\/blog\/wp-content\/uploads\/2020\/11\/Logotipo.png","width":478,"height":168,"caption":"XLabs Security"},"image":{"@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/xlabs.security","https:\/\/www.linkedin.com\/company\/xlabs-security\/","https:\/\/www.youtube.com\/channel\/UCPbGDmCQI7_UcAPmvVLi58g?view_as=subscriber","https:\/\/www.facebook.com\/xlabs"]},{"@type":"Person","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/186fa2419710709368bfa220767edb4b","name":"Evelyn Rocha","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.xlabs.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbfd8fc83a660edc367ca0dfbbb18e2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbfd8fc83a660edc367ca0dfbbb18e2e?s=96&d=mm&r=g","caption":"Evelyn Rocha"},"sameAs":["http:\/\/www.xlabs.com.br"],"url":"https:\/\/www.xlabs.com.br\/blog\/author\/evelyn-rocha\/"}]}},"_links":{"self":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/1881"}],"collection":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1881"}],"version-history":[{"count":5,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/1881\/revisions"}],"predecessor-version":[{"id":2194,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/posts\/1881\/revisions\/2194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/media\/1882"}],"wp:attachment":[{"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.xlabs.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}